{"id":1529,"date":"2025-01-24T12:16:26","date_gmt":"2025-01-24T17:16:26","guid":{"rendered":"https:\/\/pprc.ca\/?post_type=success_story&#038;p=1529"},"modified":"2025-01-24T12:16:30","modified_gmt":"2025-01-24T17:16:30","slug":"le-pouvoir-positif-du-mentorat","status":"publish","type":"success_story","link":"https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/","title":{"rendered":"Le Pouvoir Positif du Mentorat"},"content":{"rendered":"<p class=\"wp-block-paragraph\">\u201cLe plus grand cadeau que vous puissiez offrir \u00e0 quelqu&rsquo;un est le cadeau de l&rsquo;orientation et du mentorat.\u201d \u2013 Simon Sinek<\/p><p class=\"wp-block-paragraph\"><span style=\"font-family: Calibri, sans-serif; font-size: 14pt; white-space: normal;\">Le mentorat a \u00e9t\u00e9 d\u00e9fini de nombreuses fa\u00e7ons, g\u00e9n\u00e9ralement dans un contexte d&#8217;emploi. Un mentor peut \u00eatre une personne plus exp\u00e9riment\u00e9e qui guide quelqu&rsquo;un de moins exp\u00e9riment\u00e9 pour acqu\u00e9rir des connaissances sur sa carri\u00e8re choisie. Un mentor est consid\u00e9r\u00e9 comme prenant un prot\u00e9g\u00e9 \u00ab\u00a0sous son aile\u00a0\u00bb afin qu&rsquo;un coll\u00e8gue plus jeune ait des opportunit\u00e9s de grandir professionnellement et de s&rsquo;\u00e9panouir sur le lieu de travail.<\/span><\/p><p class=\"wp-block-paragraph\">Mais que faire si vous \u00eates quelqu&rsquo;un pour qui m\u00eame ouvrir la porte de l&#8217;emploi signifie surmonter de nombreux obstacles ? C&rsquo;est souvent la situation des personnes handicap\u00e9es. Ici, en Ontario, par exemple, le taux d&#8217;emploi des personnes handicap\u00e9es (58%) est toujours en retard par rapport \u00e0 celui de leurs pairs non handicap\u00e9s (81%). Certains chercheurs d&#8217;emploi handicap\u00e9s rencontrent \u00e9galement des obstacles suppl\u00e9mentaires pour trouver un emploi, comme \u00eatre nouveaux arrivants au Canada sans exp\u00e9rience de travail canadienne ou d&rsquo;autres formes de marginalisation.<\/p><p class=\"wp-block-paragraph\">Pour les chercheurs d&#8217;emploi ayant une exp\u00e9rience de vie avec un handicap, le mentorat offre une approche intentionnelle ; il les aide \u00e0 toucher le march\u00e9 du travail avant de commencer leur recherche d&#8217;emploi. Une exp\u00e9rience de mentorat peut \u00e9galement solidifier un objectif de carri\u00e8re. De plus, nous avons vu nos clients gagner en confiance en eux gr\u00e2ce au mentorat. C&rsquo;est pourquoi Performance Plus Soins en R\u00e9adaptation inc. (PPSR) a d\u00e9cid\u00e9 d&rsquo;adopter le mentorat.<\/p><p class=\"wp-block-paragraph\">PPSR est enti\u00e8rement bilingue, canadienne et bas\u00e9e \u00e0 Ottawa. Fond\u00e9e en 1994, nous fournissons des services d&rsquo;\u00e9valuation, incluant mesures d&rsquo;adaptation et de r\u00e9adaptation professionnelle aux personnes handicap\u00e9es cherchant \u00e0 entrer ou \u00e0 r\u00e9int\u00e9grer le march\u00e9 du travail. En tant que fournisseur de services approuv\u00e9 par le minist\u00e8re du Travail, de l&rsquo;Immigration, de la Formation et du D\u00e9veloppement des comp\u00e9tences (MTIFDC), Services d\u2019emploi int\u00e9gr\u00e9s, nous aidons les clients d&rsquo;Ottawa et des environs avec la planification d&#8217;emploi et les placements professionnels.<\/p><p class=\"wp-block-paragraph\">PPSR a lanc\u00e9 ses efforts de mentorat en 2020, et en 2023, nous avons marqu\u00e9 notre service comme PPSR Connect, un service prototype reliant les chercheurs d&#8217;emploi avec des employeurs des secteurs public, priv\u00e9 et \u00e0 but non lucratif. Nos clients ont recherch\u00e9 un mentorat dans des carri\u00e8res telles que l&rsquo;administration, les communications, l&rsquo;analyse des politiques, les services sociaux, l&rsquo;informatique, les soins de sant\u00e9 et le soutien personnel, le service \u00e0 la client\u00e8le et la vente au d\u00e9tail, l&rsquo;inspection de la s\u00e9curit\u00e9 alimentaire, et m\u00eame la menuiserie. Notre travail a \u00e9galement inclus deux \u00e9v\u00e9nements de partenariat de mentorat avec la Ville d&rsquo;Ottawa (2022 &amp; 2024).<\/p><p class=\"wp-block-paragraph\">Bien que le but premier du mentorat soit de fournir une exp\u00e9rience d&rsquo;apprentissage informative et qu&rsquo;il n&rsquo;y ait aucune attente de recrutement, certains de nos clients ont \u00e9t\u00e9 offerts un emploi dans des situations o\u00f9 le talent r\u00e9pond aux besoins de l&#8217;employeur.<\/p><p class=\"wp-block-paragraph\">Depuis 2020, nous avons r\u00e9alis\u00e9 75 sessions de mentorat ou correspondances de mentorat comme nous les appelons, avec d&rsquo;autres pr\u00e9vues pour l&rsquo;avenir. Les correspondances de mentorat prennent la forme d&rsquo;une session unique tenue dans ce que nous nous effor\u00e7ons de rendre un espace respectueux et confidentiel. Les correspondances peuvent avoir lieu virtuellement ou de plus en plus sur place au travail. La coordinatrice de PPSR Connect, Susan Forster, pr\u00e9pare \u00e0 la fois le mentor et le prot\u00e9g\u00e9, et assiste aux correspondances pour faciliter le processus. Notre objectif est que la correspondance devienne une conversation entre le mentor et le prot\u00e9g\u00e9, et qu&rsquo;elle remplisse ainsi son but premier d&rsquo;\u00e9change de connaissances informatif.<\/p><p class=\"wp-block-paragraph\">Lorsque l&rsquo;un de nos chercheurs d&#8217;emploi, Halim Cherchari, qui a une exp\u00e9rience de vie avec un handicap et qui est \u00e9galement un nouvel arrivant au Canada, a accept\u00e9 de participer \u00e0 PPSR Connect, il voulait en savoir plus sur le m\u00e9tier d&rsquo;inspecteur de la s\u00e9curit\u00e9 alimentaire pour le gouvernement de l&rsquo;Ontario. La coordinatrice Susan Forster a approch\u00e9 le minist\u00e8re de l&rsquo;Agriculture, de l&rsquo;Alimentation et l&rsquo;Agroentreprise de l&rsquo;Ontario (OMAFA) pour obtenir un mentor, et nous \u00e9tions ravis que notre demande ait \u00e9t\u00e9 accueillie positivement.<\/p><p class=\"has-theme-black-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\"><a>Apr\u00e8s un appel initial avec la directrice Tanya Weber-Kinch, directrice de la Direction de l\u2019inspection de la salubrit\u00e9 des aliments (FSIDB), Tim Metzger, chef, Inspection des viandes, r\u00e9gion de l\u2019Est, et Kim Landers, chef de l\u2019Unit\u00e9 des programmes d&rsquo;inspection (supervise les produits laitiers et les aliments d&rsquo;origine v\u00e9g\u00e9tale), Kim a accept\u00e9 de devenir le mentor de Halim.<\/a><\/p><p class=\"wp-block-paragraph\">Halim a travaill\u00e9 avec la coordinatrice de PPSR Connect pour cr\u00e9er une liste de questions \u00e0 poser \u00e0 son mentor. Il avait des questions telles que quelles comp\u00e9tences et quelle formation sont n\u00e9cessaires pour devenir inspecteur de la s\u00e9curit\u00e9 alimentaire et comment construire une carri\u00e8re dans la fonction publique de l&rsquo;Ontario \u00e0 l&rsquo;OMAFA ? Il a \u00e9galement appris que l&rsquo;OMAFA accueille les personnes handicap\u00e9es conform\u00e9ment \u00e0 l&rsquo;engagement du minist\u00e8re envers la politique et les proc\u00e9dures de la Loi sur l&rsquo;accessibilit\u00e9 pour les personnes handicap\u00e9es de l&rsquo;Ontario (LAPHO). Halim \u00e9tait particuli\u00e8rement int\u00e9ress\u00e9 \u00e0 apprendre comment postuler \u00e0 des emplois au minist\u00e8re, et comment personnaliser son CV et sa lettre de motivation.<\/p><p class=\"wp-block-paragraph\">Apr\u00e8s la correspondance avec Halim, Kim a comment\u00e9 : \u00ab\u00a0C&rsquo;\u00e9tait formidable d&rsquo;entendre qu&rsquo;il existe des services pour soutenir les personnes handicap\u00e9es \u00e0 trouver des carri\u00e8res significatives. J&rsquo;esp\u00e8re avoir pu donner un bon aper\u00e7u du r\u00f4le d&rsquo;un inspecteur de la s\u00e9curit\u00e9 alimentaire au sein de notre minist\u00e8re.\u00a0\u00bb<\/p><p class=\"wp-block-paragraph\">De son c\u00f4t\u00e9, Halim a trouv\u00e9 son exp\u00e9rience avec un mentor positive. Comme il l&rsquo;a dit, \u00ab\u00a0Cela aide beaucoup, surtout si vous parlez avec une personne ayant une exp\u00e9rience pertinente. La correspondance m&rsquo;a donn\u00e9 l&rsquo;opportunit\u00e9 de savoir ce qu&rsquo;il faut mettre en avant dans mon CV, et maintenant je sais ce dont ils ont besoin, quand et comment ils recrutent. J&rsquo;ai appr\u00e9ci\u00e9 les informations que j&rsquo;ai re\u00e7ues de Kim.\u00a0\u00bb Bien s\u00fbr, Kim a \u00e9galement eu des choses positives \u00e0 dire sur son exp\u00e9rience de conversation avec Halim. Elle a remarqu\u00e9, \u00ab\u00a0Halim a de nombreuses comp\u00e9tences transf\u00e9rables qui pourraient b\u00e9n\u00e9ficier \u00e0 un employeur dans l&rsquo;industrie alimentaire et semble tr\u00e8s d\u00e9sireux de travailler pour la fonction publique. Son approche positive et sa volont\u00e9 d&rsquo;en savoir plus sur les opportunit\u00e9s \u00e9taient \u00e9videntes, et c&rsquo;\u00e9tait un plaisir de discuter avec lui. Je lui souhaite bonne chance dans sa recherche de carri\u00e8re pour trouver son r\u00f4le parfait.\u00a0\u00bb<\/p><p class=\"wp-block-paragraph\">Merci beaucoup au personnel du minist\u00e8re qui a rendu cette correspondance de mentorat possible, en particulier \u00e0 Stacy Pinkney, adjointe de direction, qui a facilit\u00e9 les premiers contacts. Nous accueillons favorablement d&rsquo;autres opportunit\u00e9s de partenariat avec l&rsquo;OMAFA et d&rsquo;autres minist\u00e8res du gouvernement de l&rsquo;Ontario pour soutenir les chercheurs d&#8217;emploi handicap\u00e9s alors qu&rsquo;ils franchissent leurs premi\u00e8res \u00e9tapes vers l&rsquo;objectif de trouver un emploi.<\/p><p class=\"wp-block-paragraph\">Pour en savoir plus sur PPSR Connect, contactez Susan Forster, coordinatrice, \u00e0 sforster@pprc.ca et visitez\u00a0<a href=\"https:\/\/pprc.ca\/fr\/le-choix-dune-nouvelle-carriere\/programme-de-mentorat\/\">Formulaires de services aux personnes handicap\u00e9es | Services professionnels \u2013 Programme de mentorat<\/a>.<\/p><p class=\"wp-block-paragraph\">Pour en savoir plus sur les services bilingues de r\u00e9adaptation professionnelle de PPRC, rendez-vous sur\u00a0\u00a0<a href=\"https:\/\/pprc.ca\/fr\/\">Soutien aux personnes handicap\u00e9es \u00e0 Ottawa | Performance Plus<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u201cLe plus grand cadeau que vous puissiez offrir \u00e0 quelqu&rsquo;un est le cadeau de l&rsquo;orientation et du mentorat.\u201d \u2013 Simon Sinek Le mentorat a \u00e9t\u00e9 d\u00e9fini de nombreuses fa\u00e7ons, g\u00e9n\u00e9ralement dans un contexte d&#8217;emploi. Un mentor peut \u00eatre une personne plus exp\u00e9riment\u00e9e qui guide quelqu&rsquo;un de moins exp\u00e9riment\u00e9 pour acqu\u00e9rir des connaissances sur sa carri\u00e8re [&hellip;]<\/p>\n","protected":false},"featured_media":1527,"template":"","class_list":["post-1529","success_story","type-success_story","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Pouvoir Positif du Mentorat - Performance Plus - Soins en R\u00e9adaptation inc.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Pouvoir Positif du Mentorat - Performance Plus - Soins en R\u00e9adaptation inc.\" \/>\n<meta property=\"og:description\" content=\"\u201cLe plus grand cadeau que vous puissiez offrir \u00e0 quelqu&rsquo;un est le cadeau de l&rsquo;orientation et du mentorat.\u201d \u2013 Simon Sinek Le mentorat a \u00e9t\u00e9 d\u00e9fini de nombreuses fa\u00e7ons, g\u00e9n\u00e9ralement dans un contexte d&#8217;emploi. Un mentor peut \u00eatre une personne plus exp\u00e9riment\u00e9e qui guide quelqu&rsquo;un de moins exp\u00e9riment\u00e9 pour acqu\u00e9rir des connaissances sur sa carri\u00e8re [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/\" \/>\n<meta property=\"og:site_name\" content=\"Performance Plus - Soins en R\u00e9adaptation inc.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Performance-Plus-Rehabilitative-Care-Inc-172441926133114\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-24T17:16:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pprc.ca\/wp-content\/uploads\/2025\/01\/disabled-food-inspector-at-work-in-field-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PPRCOttawa\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/\",\"url\":\"https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/\",\"name\":\"Le Pouvoir Positif du Mentorat - Performance Plus - Soins en R\u00e9adaptation inc.\",\"isPartOf\":{\"@id\":\"https:\/\/pprc.ca\/fr\/#website\"},\"datePublished\":\"2025-01-24T17:16:26+00:00\",\"dateModified\":\"2025-01-24T17:16:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/pprc.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Pouvoir Positif du Mentorat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pprc.ca\/fr\/#website\",\"url\":\"https:\/\/pprc.ca\/fr\/\",\"name\":\"Performance Plus - Soins en R\u00e9adaptation inc.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/pprc.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pprc.ca\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pprc.ca\/fr\/#organization\",\"name\":\"Performance Plus - Soins en R\u00e9adaptation inc.\",\"url\":\"https:\/\/pprc.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/pprc.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pprc.ca\/wp-content\/uploads\/2022\/12\/PPSR-logo-icon-1.png\",\"contentUrl\":\"https:\/\/pprc.ca\/wp-content\/uploads\/2022\/12\/PPSR-logo-icon-1.png\",\"width\":158,\"height\":148,\"caption\":\"Performance Plus - Soins en R\u00e9adaptation inc.\"},\"image\":{\"@id\":\"https:\/\/pprc.ca\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Performance-Plus-Rehabilitative-Care-Inc-172441926133114\/\",\"https:\/\/twitter.com\/PPRCOttawa\",\"https:\/\/www.youtube.com\/channel\/UCBnhuJDUkY4Qmi94FKUKbSQ\",\"https:\/\/www.linkedin.com\/company\/performance-plus-rehabilitative-care-inc.\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Pouvoir Positif du Mentorat - Performance Plus - Soins en R\u00e9adaptation inc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Pouvoir Positif du Mentorat - Performance Plus - Soins en R\u00e9adaptation inc.","og_description":"\u201cLe plus grand cadeau que vous puissiez offrir \u00e0 quelqu&rsquo;un est le cadeau de l&rsquo;orientation et du mentorat.\u201d \u2013 Simon Sinek Le mentorat a \u00e9t\u00e9 d\u00e9fini de nombreuses fa\u00e7ons, g\u00e9n\u00e9ralement dans un contexte d&#8217;emploi. Un mentor peut \u00eatre une personne plus exp\u00e9riment\u00e9e qui guide quelqu&rsquo;un de moins exp\u00e9riment\u00e9 pour acqu\u00e9rir des connaissances sur sa carri\u00e8re [&hellip;]","og_url":"https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/","og_site_name":"Performance Plus - Soins en R\u00e9adaptation inc.","article_publisher":"https:\/\/www.facebook.com\/Performance-Plus-Rehabilitative-Care-Inc-172441926133114\/","article_modified_time":"2025-01-24T17:16:30+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/pprc.ca\/wp-content\/uploads\/2025\/01\/disabled-food-inspector-at-work-in-field-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@PPRCOttawa","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/","url":"https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/","name":"Le Pouvoir Positif du Mentorat - Performance Plus - Soins en R\u00e9adaptation inc.","isPartOf":{"@id":"https:\/\/pprc.ca\/fr\/#website"},"datePublished":"2025-01-24T17:16:26+00:00","dateModified":"2025-01-24T17:16:30+00:00","breadcrumb":{"@id":"https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pprc.ca\/fr\/histoires-a-succes\/le-pouvoir-positif-du-mentorat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/pprc.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Le Pouvoir Positif du Mentorat"}]},{"@type":"WebSite","@id":"https:\/\/pprc.ca\/fr\/#website","url":"https:\/\/pprc.ca\/fr\/","name":"Performance Plus - Soins en R\u00e9adaptation inc.","description":"","publisher":{"@id":"https:\/\/pprc.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pprc.ca\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/pprc.ca\/fr\/#organization","name":"Performance Plus - Soins en R\u00e9adaptation inc.","url":"https:\/\/pprc.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pprc.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/pprc.ca\/wp-content\/uploads\/2022\/12\/PPSR-logo-icon-1.png","contentUrl":"https:\/\/pprc.ca\/wp-content\/uploads\/2022\/12\/PPSR-logo-icon-1.png","width":158,"height":148,"caption":"Performance Plus - Soins en R\u00e9adaptation inc."},"image":{"@id":"https:\/\/pprc.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Performance-Plus-Rehabilitative-Care-Inc-172441926133114\/","https:\/\/twitter.com\/PPRCOttawa","https:\/\/www.youtube.com\/channel\/UCBnhuJDUkY4Qmi94FKUKbSQ","https:\/\/www.linkedin.com\/company\/performance-plus-rehabilitative-care-inc.\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pprc.ca\/fr\/wp-json\/wp\/v2\/success_story\/1529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pprc.ca\/fr\/wp-json\/wp\/v2\/success_story"}],"about":[{"href":"https:\/\/pprc.ca\/fr\/wp-json\/wp\/v2\/types\/success_story"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pprc.ca\/fr\/wp-json\/wp\/v2\/media\/1527"}],"wp:attachment":[{"href":"https:\/\/pprc.ca\/fr\/wp-json\/wp\/v2\/media?parent=1529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}